{"id":16606,"date":"2025-09-24T07:30:00","date_gmt":"2025-09-24T10:30:00","guid":{"rendered":"https:\/\/www.radiomanchester.com.br\/fm\/?p=16606"},"modified":"2025-09-23T22:08:54","modified_gmt":"2025-09-24T01:08:54","slug":"a-defesa-de-bolsonaro-esta-preparando-um-pedido-pelo-fim-da-prisao-domiciliar","status":"publish","type":"post","link":"https:\/\/www.radiomanchester.com.br\/fm\/a-defesa-de-bolsonaro-esta-preparando-um-pedido-pelo-fim-da-prisao-domiciliar\/","title":{"rendered":"A defesa de Bolsonaro est\u00e1 preparando um pedido pelo fim da pris\u00e3o domiciliar"},"content":{"rendered":"\n<p>A defesa do ex-presidente Jair Bolsonaro (PL) est\u00e1 preparando um pedido a ser enviado ao ministro Alexandre de Moraes, do Supremo Tribunal Federal (STF), para solicitar o fim da pris\u00e3o domiciliar de Bolsonaro.<\/p>\n\n\n\n<p>A informa\u00e7\u00e3o foi confirmada pelo Metr\u00f3poles com os representantes do ex-presidente. Na \u00faltima segunda-feira (23\/09), a Procuradoria-Geral da Rep\u00fablica (PGR) denunciou, no \u00e2mbito do inqu\u00e9rito 4995, o deputado federal Eduardo Bolsonaro (PL) e o blogueiro Paulo Figueiredo por coa\u00e7\u00e3o no processo judicial.<\/p>\n\n\n\n<p>A pris\u00e3o domiciliar de Bolsonaro foi decretada por Moraes com base no mesmo inqu\u00e9rito. Tendo em vista a n\u00e3o den\u00fancia do ex-presidente, a defesa deve pedir para que seja revogada a pris\u00e3o domiciliar e outras medidas cautelares impostas.<\/p>\n\n\n\n<p>Bolsonaro est\u00e1 com tornozeleira eletr\u00f4nica, proibido de se aproximar e ter acesso a sedes de embaixadas e consulados, al\u00e9m de manter contatos com embaixadores ou autoridades estrangeiras. \u00c0 \u00e9poca, Moraes tamb\u00e9m determinou a proibi\u00e7\u00e3o do uso de redes sociais por parte do ex-presidente.<\/p>\n\n\n\n<p>porR3pMetr0p0les parceiro Manchester<\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"excerpt\">A defesa do ex-presidente Jair Bolsonaro (PL) est\u00e1 preparando um pedido a ser enviado ao ministro Alexandre de Moraes, do Supremo Tribunal Federal (STF), para solicitar o fim da pris\u00e3o domiciliar de Bolsonaro. A informa\u00e7\u00e3o foi confirmada pelo Metr\u00f3poles com os representantes do ex-presidente. Na \u00faltima segunda-feira (23\/09), a Procuradoria-Geral da Rep\u00fablica (PGR) denunciou, no [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[8,17],"tags":[22,24,113,83,92],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A defesa de Bolsonaro est\u00e1 preparando um pedido pelo fim da pris\u00e3o domiciliar - Manchester FM 93,3<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.radiomanchester.com.br\/fm\/a-defesa-de-bolsonaro-esta-preparando-um-pedido-pelo-fim-da-prisao-domiciliar\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A defesa de Bolsonaro est\u00e1 preparando um pedido pelo fim da pris\u00e3o domiciliar - Manchester FM 93,3\" \/>\n<meta property=\"og:description\" content=\"A defesa do ex-presidente Jair Bolsonaro (PL) est\u00e1 preparando um pedido a ser enviado ao ministro Alexandre de Moraes, do Supremo Tribunal Federal (STF), para solicitar o fim da pris\u00e3o domiciliar de Bolsonaro. A informa\u00e7\u00e3o foi confirmada pelo Metr\u00f3poles com os representantes do ex-presidente. Na \u00faltima segunda-feira (23\/09), a Procuradoria-Geral da Rep\u00fablica (PGR) denunciou, no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.radiomanchester.com.br\/fm\/a-defesa-de-bolsonaro-esta-preparando-um-pedido-pelo-fim-da-prisao-domiciliar\/\" \/>\n<meta property=\"og:site_name\" content=\"Manchester FM 93,3\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-24T10:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-24T01:08:54+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.radiomanchester.com.br\/fm\/#website\",\"url\":\"https:\/\/www.radiomanchester.com.br\/fm\/\",\"name\":\"Manchester FM 93,3\",\"description\":\"Todo Mundo Ouve!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.radiomanchester.com.br\/fm\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.radiomanchester.com.br\/fm\/a-defesa-de-bolsonaro-esta-preparando-um-pedido-pelo-fim-da-prisao-domiciliar\/#webpage\",\"url\":\"https:\/\/www.radiomanchester.com.br\/fm\/a-defesa-de-bolsonaro-esta-preparando-um-pedido-pelo-fim-da-prisao-domiciliar\/\",\"name\":\"A defesa de Bolsonaro est\u00e1 preparando um pedido pelo fim da pris\u00e3o domiciliar - Manchester FM 93,3\",\"isPartOf\":{\"@id\":\"https:\/\/www.radiomanchester.com.br\/fm\/#website\"},\"datePublished\":\"2025-09-24T10:30:00+00:00\",\"dateModified\":\"2025-09-24T01:08:54+00:00\",\"author\":{\"@id\":\"https:\/\/www.radiomanchester.com.br\/fm\/#\/schema\/person\/408a7b4d4e32cbebd90e2782852abca3\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.radiomanchester.com.br\/fm\/a-defesa-de-bolsonaro-esta-preparando-um-pedido-pelo-fim-da-prisao-domiciliar\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.radiomanchester.com.br\/fm\/a-defesa-de-bolsonaro-esta-preparando-um-pedido-pelo-fim-da-prisao-domiciliar\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.radiomanchester.com.br\/fm\/a-defesa-de-bolsonaro-esta-preparando-um-pedido-pelo-fim-da-prisao-domiciliar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.radiomanchester.com.br\/fm\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A defesa de Bolsonaro est\u00e1 preparando um pedido pelo fim da pris\u00e3o domiciliar\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.radiomanchester.com.br\/fm\/#\/schema\/person\/408a7b4d4e32cbebd90e2782852abca3\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.radiomanchester.com.br\/fm\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/115a974dba3376872eb3addeb276301c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/115a974dba3376872eb3addeb276301c?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\/\/www.radiomanchester.com.br\/fm\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A defesa de Bolsonaro est\u00e1 preparando um pedido pelo fim da pris\u00e3o domiciliar - Manchester FM 93,3","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.radiomanchester.com.br\/fm\/a-defesa-de-bolsonaro-esta-preparando-um-pedido-pelo-fim-da-prisao-domiciliar\/","og_locale":"pt_BR","og_type":"article","og_title":"A defesa de Bolsonaro est\u00e1 preparando um pedido pelo fim da pris\u00e3o domiciliar - Manchester FM 93,3","og_description":"A defesa do ex-presidente Jair Bolsonaro (PL) est\u00e1 preparando um pedido a ser enviado ao ministro Alexandre de Moraes, do Supremo Tribunal Federal (STF), para solicitar o fim da pris\u00e3o domiciliar de Bolsonaro. A informa\u00e7\u00e3o foi confirmada pelo Metr\u00f3poles com os representantes do ex-presidente. Na \u00faltima segunda-feira (23\/09), a Procuradoria-Geral da Rep\u00fablica (PGR) denunciou, no [&hellip;]","og_url":"https:\/\/www.radiomanchester.com.br\/fm\/a-defesa-de-bolsonaro-esta-preparando-um-pedido-pelo-fim-da-prisao-domiciliar\/","og_site_name":"Manchester FM 93,3","article_published_time":"2025-09-24T10:30:00+00:00","article_modified_time":"2025-09-24T01:08:54+00:00","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.radiomanchester.com.br\/fm\/#website","url":"https:\/\/www.radiomanchester.com.br\/fm\/","name":"Manchester FM 93,3","description":"Todo Mundo Ouve!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.radiomanchester.com.br\/fm\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.radiomanchester.com.br\/fm\/a-defesa-de-bolsonaro-esta-preparando-um-pedido-pelo-fim-da-prisao-domiciliar\/#webpage","url":"https:\/\/www.radiomanchester.com.br\/fm\/a-defesa-de-bolsonaro-esta-preparando-um-pedido-pelo-fim-da-prisao-domiciliar\/","name":"A defesa de Bolsonaro est\u00e1 preparando um pedido pelo fim da pris\u00e3o domiciliar - Manchester FM 93,3","isPartOf":{"@id":"https:\/\/www.radiomanchester.com.br\/fm\/#website"},"datePublished":"2025-09-24T10:30:00+00:00","dateModified":"2025-09-24T01:08:54+00:00","author":{"@id":"https:\/\/www.radiomanchester.com.br\/fm\/#\/schema\/person\/408a7b4d4e32cbebd90e2782852abca3"},"breadcrumb":{"@id":"https:\/\/www.radiomanchester.com.br\/fm\/a-defesa-de-bolsonaro-esta-preparando-um-pedido-pelo-fim-da-prisao-domiciliar\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.radiomanchester.com.br\/fm\/a-defesa-de-bolsonaro-esta-preparando-um-pedido-pelo-fim-da-prisao-domiciliar\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.radiomanchester.com.br\/fm\/a-defesa-de-bolsonaro-esta-preparando-um-pedido-pelo-fim-da-prisao-domiciliar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.radiomanchester.com.br\/fm\/"},{"@type":"ListItem","position":2,"name":"A defesa de Bolsonaro est\u00e1 preparando um pedido pelo fim da pris\u00e3o domiciliar"}]},{"@type":"Person","@id":"https:\/\/www.radiomanchester.com.br\/fm\/#\/schema\/person\/408a7b4d4e32cbebd90e2782852abca3","name":"admin","image":{"@type":"ImageObject","@id":"https:\/\/www.radiomanchester.com.br\/fm\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/115a974dba3376872eb3addeb276301c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/115a974dba3376872eb3addeb276301c?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/www.radiomanchester.com.br\/fm\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.radiomanchester.com.br\/fm\/wp-json\/wp\/v2\/posts\/16606"}],"collection":[{"href":"https:\/\/www.radiomanchester.com.br\/fm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.radiomanchester.com.br\/fm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.radiomanchester.com.br\/fm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.radiomanchester.com.br\/fm\/wp-json\/wp\/v2\/comments?post=16606"}],"version-history":[{"count":1,"href":"https:\/\/www.radiomanchester.com.br\/fm\/wp-json\/wp\/v2\/posts\/16606\/revisions"}],"predecessor-version":[{"id":16607,"href":"https:\/\/www.radiomanchester.com.br\/fm\/wp-json\/wp\/v2\/posts\/16606\/revisions\/16607"}],"wp:attachment":[{"href":"https:\/\/www.radiomanchester.com.br\/fm\/wp-json\/wp\/v2\/media?parent=16606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.radiomanchester.com.br\/fm\/wp-json\/wp\/v2\/categories?post=16606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.radiomanchester.com.br\/fm\/wp-json\/wp\/v2\/tags?post=16606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}